{"id":14085,"date":"2018-09-12T11:34:34","date_gmt":"2018-09-12T17:34:34","guid":{"rendered":"https:\/\/clicstudyinchina.com\/?post_type=tribe_venue&#038;p=14085"},"modified":"2018-11-02T10:18:33","modified_gmt":"2018-11-02T16:18:33","slug":"universite-chinoise-de-science-politique-et-de-droit-beijing","status":"publish","type":"tribe_venue","link":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/","title":{"rendered":"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":0,"template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-14085","tribe_venue","type-tribe_venue","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/\" \/>\n<meta property=\"og:site_name\" content=\"CLIC\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-02T16:18:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/universite\\\/universite-chinoise-de-science-politique-et-de-droit-beijing\\\/\",\"url\":\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/universite\\\/universite-chinoise-de-science-politique-et-de-droit-beijing\\\/\",\"name\":\"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clicstudyinchina.com\\\/#website\"},\"datePublished\":\"2018-09-12T17:34:34+00:00\",\"dateModified\":\"2018-11-02T16:18:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/universite\\\/universite-chinoise-de-science-politique-et-de-droit-beijing\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/universite\\\/universite-chinoise-de-science-politique-et-de-droit-beijing\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/universite\\\/universite-chinoise-de-science-politique-et-de-droit-beijing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clicstudyinchina.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clicstudyinchina.com\\\/#website\",\"url\":\"https:\\\/\\\/clicstudyinchina.com\\\/\",\"name\":\"CLIC\",\"description\":\"Canada Learning Initiative in China\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clicstudyinchina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/","og_locale":"fr_FR","og_type":"article","og_title":"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC","og_url":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/","og_site_name":"CLIC","article_modified_time":"2018-11-02T16:18:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/","url":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/","name":"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin - CLIC","isPartOf":{"@id":"https:\/\/clicstudyinchina.com\/#website"},"datePublished":"2018-09-12T17:34:34+00:00","dateModified":"2018-11-02T16:18:33+00:00","breadcrumb":{"@id":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clicstudyinchina.com\/fr\/universite\/universite-chinoise-de-science-politique-et-de-droit-beijing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clicstudyinchina.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Universit\u00e9 chinoise de science politique et de droit, P\u00e9kin"}]},{"@type":"WebSite","@id":"https:\/\/clicstudyinchina.com\/#website","url":"https:\/\/clicstudyinchina.com\/","name":"CLIC","description":"Canada Learning Initiative in China","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clicstudyinchina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/tribe_venue\/14085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/types\/tribe_venue"}],"author":[{"embeddable":true,"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"version-history":[{"count":0,"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/tribe_venue\/14085\/revisions"}],"wp:attachment":[{"href":"https:\/\/clicstudyinchina.com\/fr\/wp-json\/wp\/v2\/media?parent=14085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}